{"id":1231,"date":"2017-04-03T10:43:00","date_gmt":"2017-04-03T10:43:00","guid":{"rendered":"http:\/\/drpreema.wwwnl1-ss14.a2hosted.com\/de-stress-your-life-for-good\/"},"modified":"2020-03-30T13:07:37","modified_gmt":"2020-03-30T13:07:37","slug":"desestresate-para-siempre","status":"publish","type":"post","link":"https:\/\/drpreema.com\/es\/de-stress-your-life-for-good\/","title":{"rendered":"Desestr\u00e9sate para siempre"},"content":{"rendered":"<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"230\" src=\"https:\/\/i0.wp.com\/drpreema.com\/wp-content\/uploads\/2020\/03\/skin-stress.jpg?resize=300%2C230&#038;ssl=1\" alt=\"\" class=\"wp-image-1468\"\/><\/figure><\/div>\n\n\n\n<p>Muchos de nosotros pasamos la vida haciendo malabarismos con demasiadas cosas, pero \u00bfllevar una vida estresante podr\u00eda estar afect\u00e1ndonos de maneras que ni siquiera nos damos cuenta?<\/p>\n\n\n\n<p>Ya sea un trabajo exigente, una relaci\u00f3n que exige mucho esfuerzo o una familia de ni\u00f1os muy nerviosos, muchos de nosotros sufrimos estr\u00e9s, un estado de tensi\u00f3n o tensi\u00f3n mental o emocional.<\/p>\n\n\n\n<p>Aqu\u00ed descubrimos c\u00f3mo nos afecta el estr\u00e9s y c\u00f3mo podemos combatirlo\u2026<\/p>\n\n\n\n<p><strong>PIEL<\/strong><\/p>\n\n\n\n<p>\u201cEl cortisol desencadena la inflamaci\u00f3n y afecta la renovaci\u00f3n celular de la piel. Por lo tanto, las c\u00e9lulas muertas se acumulan, dando al rostro un aspecto opaco y sin vida\u201d, explica la Dra. Preema Vig. \u201cTambi\u00e9n provoca un aumento de la producci\u00f3n de grasa, lo que obstruye los poros y provoca brotes de acn\u00e9\u201d.<\/p>\n\n\n\n<p>CONSEJOS CLAVE: \u00abLas exfoliaciones regulares realzar\u00e1n la luminosidad de la piel\u00bb, recomienda Preema. \u00abMant\u00e9n la piel limpia de suciedad superficial, grasa y c\u00e9lulas muertas, pero no la frotes, ya que esto puede irritar el acn\u00e9\u00bb.<\/p>","protected":false},"excerpt":{"rendered":"<p>Many of us spend our lives juggling too much \u2013 but could leading a frazzled life be affecting us in ways we don\u2019t even realise? Whether it\u2019s a high-flying job, a high maintenance relationship, or a brood of highly-strung children, many of us suffer from stress \u2013 a state of mental or emotional strain or [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1467,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_news_disabled":"","_seopress_video_disabled":"","_seopress_video":[],"_seopress_pro_schemas_manual":[],"_seopress_pro_rich_snippets_disable_all":"","_seopress_pro_rich_snippets_disable":[],"_seopress_pro_schemas":[],"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-1231","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-press"},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/drpreema.com\/wp-content\/uploads\/2020\/03\/new_logo-copy-1.jpg?fit=442%2C442&ssl=1&wsr","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/posts\/1231","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/comments?post=1231"}],"version-history":[{"count":4,"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/posts\/1231\/revisions"}],"predecessor-version":[{"id":1471,"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/posts\/1231\/revisions\/1471"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/media\/1467"}],"wp:attachment":[{"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/media?parent=1231"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/categories?post=1231"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drpreema.com\/es\/wp-json\/wp\/v2\/tags?post=1231"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}